{"id":1866,"date":"2017-06-06T17:32:46","date_gmt":"2017-06-06T20:32:46","guid":{"rendered":"http:\/\/www.agitah.com\/novo\/2017\/06\/06\/erasmo-vianna-pede-a-mao-de-gabriela-pugliesi-em-casamento\/"},"modified":"2017-06-06T17:32:46","modified_gmt":"2017-06-06T20:32:46","slug":"erasmo-vianna-pede-a-mao-de-gabriela-pugliesi-em-casamento","status":"publish","type":"post","link":"https:\/\/www.agitah.com\/novo\/erasmo-vianna-pede-a-mao-de-gabriela-pugliesi-em-casamento\/","title":{"rendered":"Erasmo Vianna pede a m\u00e3o de Gabriela Pugliesi em casamento"},"content":{"rendered":"<p>\n\t<span style=\"font-size:14px\">Gabriela Pugliesi vai se casar. A musa fitness ficou noiva do personal trainer Erasmo Vianna nesta sexta-feira. O pedido foi feito a bordo de um iate durante uma viagem do casal pelas ilhas gregas.<\/span><\/p>\n<p>\n\t<span style=\"font-size:14px\">O bonit&atilde;o contratou at&eacute; uma mo&ccedil;a para tocar harpa na hora de pedir &agrave; m&atilde;o da amada. Ap&oacute;s a aceitar o pedido, a gata aplaudiu o sol ao lado do futuro marido. A blogueira, claro, registrou tudo em seu perfil no Snapchat. &ldquo;Agora posso comer p&atilde;o&rdquo;, brincou.<\/span><\/p>\n<p>\n\t<span style=\"font-size:14px\">J&aacute; Vianna foi bem mais rom&acirc;ntico ao atualizar suas redes sociais. &quot;Ela disse sim&quot;, escreveu na legenda da foto das alian&ccedil;as.<\/span><\/p>\n<p>\n\t<span style=\"font-size:14px\">A joia, feita em ouro dourado com um diamante lapidado em formato de tri&acirc;ngulo, foi desenhada pelo fort&atilde;o que tem o s&iacute;mbolo geom&eacute;trico tatuado no corpo. A imagem simboliza equil&iacute;brio entre corpo, mente e esp&iacute;rito. Al&eacute;m disso, o gato mandou gravar nas pe&ccedil;as o nome do casal com a sua caligrafia.<\/span><\/p>\n<p>\n\t<span style=\"font-size:14px\">Pugliesi e Viana est&atilde;o juntos h&aacute; quase 10 meses. Rumores d&atilde;o conta de que a beldade teria tra&iacute;do o marido, Thiago Pugliesi, com o atual companheiro. Gabriela nega a pulada de cerca e jura ter ficado com o moreno ap&oacute;s colocar um ponto final em sua uni&atilde;o de cinco anos com o empres&aacute;rio que lhe deu o sobrenome que se transformou em sin&ocirc;nimo de boa forma.<\/span><\/p>\n<p>\n\t&nbsp;<\/p>\n<p>\n\tFonte: www.famosidades.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gabriela Pugliesi vai se casar. A musa fitness ficou noiva do personal trainer Erasmo Vianna nesta sexta-feira. O pedido foi feito a bordo de um iate durante uma viagem do casal pelas ilhas gregas. O bonit&atilde;o contratou at&eacute; uma mo&ccedil;a &hellip;<\/p>\n","protected":false},"author":1,"featured_media":1867,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1866","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques"],"_links":{"self":[{"href":"https:\/\/www.agitah.com\/novo\/wp-json\/wp\/v2\/posts\/1866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agitah.com\/novo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agitah.com\/novo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agitah.com\/novo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agitah.com\/novo\/wp-json\/wp\/v2\/comments?post=1866"}],"version-history":[{"count":0,"href":"https:\/\/www.agitah.com\/novo\/wp-json\/wp\/v2\/posts\/1866\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.agitah.com\/novo\/wp-json\/wp\/v2\/media\/1867"}],"wp:attachment":[{"href":"https:\/\/www.agitah.com\/novo\/wp-json\/wp\/v2\/media?parent=1866"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agitah.com\/novo\/wp-json\/wp\/v2\/categories?post=1866"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agitah.com\/novo\/wp-json\/wp\/v2\/tags?post=1866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}