{"id":132965,"date":"2023-05-24T11:36:37","date_gmt":"2023-05-24T14:36:37","guid":{"rendered":"http:\/\/www.agitah.com\/novo\/?p=132965"},"modified":"2023-05-24T11:36:39","modified_gmt":"2023-05-24T14:36:39","slug":"espacador-e100-incoterm-closet-do-profissional","status":"publish","type":"post","link":"https:\/\/www.agitah.com\/novo\/espacador-e100-incoterm-closet-do-profissional\/","title":{"rendered":"ESPA\u00c7ADOR E100 INCOTERM &#8211; CLOSET DO PROFISSIONAL"},"content":{"rendered":"\n<p>O Espa\u00e7ador E100 Incoterm foi desenvolvido para aumentar a efic\u00e1cia dos medicamentos para tratamento da asma, bronquite e de outros problemas respirat\u00f3rios.<br>Indicado para administra\u00e7\u00e3o de medicamentos em aerossol, dispon\u00edveis em dosificadores pressurizados popularmente conhecidos por \u201cBombinhas\u201d. Este espa\u00e7ador faz com que apenas a subst\u00e2ncia ativa chegue at\u00e9 os pulm\u00f5es, auxiliando a vedar totalmente o ambiente externo, al\u00e9m melhorar a inala\u00e7\u00e3o do medicamento.<br>Permite o uso com ou sem m\u00e1scara, conforme o paciente (crian\u00e7a ou adulto) e a prescri\u00e7\u00e3o m\u00e9dica.<br>Possui encaixe universal, sendo compat\u00edvel com todos os dispensadores de medicamento aerossol.<br><br><br>Conhe\u00e7a esse e outros produtos na Closet do Profissional.<br>?Rua Cambar\u00e1, 1087 \u2013 Centro \u2013 Guarant\u00e3 do Norte (MT)<br>?(66) 9 9915-4206<br><br>#medicina<a href=\"https:\/\/www.instagram.com\/explore\/tags\/cirurgias\/\">#cirurgias<\/a><a href=\"https:\/\/www.instagram.com\/explore\/tags\/hidrolight\/\">#hidrolight<\/a>\u00a0<a href=\"https:\/\/www.instagram.com\/explore\/tags\/acedemicos\/\">#acedemicos<\/a>\u00a0<a href=\"https:\/\/www.instagram.com\/explore\/tags\/facul\/\">#facul<\/a>\u00a0<a href=\"https:\/\/www.instagram.com\/explore\/tags\/trend\/\">#trend<\/a>\u00a0<a href=\"https:\/\/www.instagram.com\/explore\/tags\/qualidadedevida\/\">#qualidadedevida<\/a>\u00a0<a href=\"https:\/\/www.instagram.com\/explore\/tags\/jalecos\/\">#jalecos<\/a>\u00a0<a href=\"https:\/\/www.instagram.com\/explore\/tags\/scrubs\/\">#scrubs<\/a>\u00a0<a href=\"https:\/\/www.instagram.com\/explore\/tags\/crossfit\/\">#crossfit<\/a>\u00a0<a href=\"https:\/\/www.instagram.com\/explore\/tags\/gym\/\">#gym<\/a>\u00a0<a href=\"https:\/\/www.instagram.com\/explore\/tags\/saudeeforma\/\">#saudeeforma<\/a> <\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.agitah.com\/novo\/wp-content\/uploads\/2023\/05\/326203637_856676555543191_2829959517107413929_n-1024x1024.jpg\" alt=\"\" class=\"wp-image-132966\" width=\"392\" height=\"392\" srcset=\"https:\/\/www.agitah.com\/novo\/wp-content\/uploads\/2023\/05\/326203637_856676555543191_2829959517107413929_n-300x300.jpg 300w, https:\/\/www.agitah.com\/novo\/wp-content\/uploads\/2023\/05\/326203637_856676555543191_2829959517107413929_n-150x150.jpg 150w\" sizes=\"auto, (max-width: 392px) 100vw, 392px\" \/><\/figure>\n\r\n","protected":false},"excerpt":{"rendered":"<p>O Espa\u00e7ador E100 Incoterm foi desenvolvido para aumentar a efic\u00e1cia dos medicamentos para tratamento da asma, bronquite e de outros problemas respirat\u00f3rios.Indicado para administra\u00e7\u00e3o de medicamentos em aerossol, dispon\u00edveis em dosificadores pressurizados popularmente conhecidos por \u201cBombinhas\u201d. Este espa\u00e7ador faz com &hellip;<\/p>\n","protected":false},"author":2,"featured_media":132966,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-132965","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques"],"_links":{"self":[{"href":"https:\/\/www.agitah.com\/novo\/wp-json\/wp\/v2\/posts\/132965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agitah.com\/novo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agitah.com\/novo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agitah.com\/novo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agitah.com\/novo\/wp-json\/wp\/v2\/comments?post=132965"}],"version-history":[{"count":1,"href":"https:\/\/www.agitah.com\/novo\/wp-json\/wp\/v2\/posts\/132965\/revisions"}],"predecessor-version":[{"id":132969,"href":"https:\/\/www.agitah.com\/novo\/wp-json\/wp\/v2\/posts\/132965\/revisions\/132969"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.agitah.com\/novo\/wp-json\/wp\/v2\/media\/132966"}],"wp:attachment":[{"href":"https:\/\/www.agitah.com\/novo\/wp-json\/wp\/v2\/media?parent=132965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agitah.com\/novo\/wp-json\/wp\/v2\/categories?post=132965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agitah.com\/novo\/wp-json\/wp\/v2\/tags?post=132965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}